{"id":298,"date":"2022-09-10T08:31:56","date_gmt":"2022-09-10T08:31:56","guid":{"rendered":"https:\/\/batirjeunesseausoleil.org\/2022\/09\/10\/dou-vient-il\/"},"modified":"2024-11-04T16:12:47","modified_gmt":"2024-11-04T16:12:47","slug":"lancement-de-campagne","status":"publish","type":"post","link":"https:\/\/batirjeunesseausoleil.org\/fr\/2022\/09\/10\/lancement-de-campagne\/","title":{"rendered":"14 millions $ pour b\u00e2tir un avenir meilleur."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"298\" class=\"elementor elementor-298 elementor-139\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f031510 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f031510\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7516376c\" data-id=\"7516376c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc14881 elementor-widget elementor-widget-image\" data-id=\"dc14881\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1536\" height=\"864\" src=\"https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/02\/Building-hiver-1536x864.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-1277\" alt=\"\" srcset=\"https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/02\/Building-hiver-1536x864.jpg 1536w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/02\/Building-hiver-300x169.jpg 300w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/02\/Building-hiver-1024x576.jpg 1024w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/02\/Building-hiver-768x432.jpg 768w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/02\/Building-hiver-2048x1152.jpg 2048w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55e3b755 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"55e3b755\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>C\u2019est sous le th\u00e8me \u00ab B\u00e2tir un avenir meilleur \u00bb<\/strong> que Jeunesse au soleil lance aujourd\u2019hui la premi\u00e8re campagne majeure de financement de son histoire pour la construction d\u2019un nouveau centre communautaire, compl\u00e8tement carboneutre, qui r\u00e9unira tous les services de l\u2019organisme sous un m\u00eame toit. La nouvelle maison de Jeunesse au soleil, dont l\u2019ouverture est pr\u00e9vue au printemps 2025, sera situ\u00e9e au 7501, boul. Saint-Laurent \u00e0 Montr\u00e9al.&nbsp;<\/p>\n<p>Pr\u00e9sid\u00e9e par Lucy Riddell, pr\u00e9sidente du Conseil de la Fondation R. Howard Webster, et Claude Mongeau, ancien PDG du CN, l\u2019objectif de la campagne est d\u2019amasser 14 millions $.<\/p>\n<p>\u00ab&nbsp;Depuis 2018, nos services sont dispers\u00e9s aux quatre coins de la Ville. Cette situation nous a confirm\u00e9 l\u2019importance de mettre en place ce projet d\u2019envergure qui nous fournira un toit pour les prochaines g\u00e9n\u00e9rations, assurera la p\u00e9rennit\u00e9 de Jeunesse au Soleil et servira, nous l\u2019esp\u00e9rons, de mod\u00e8le environnemental pour les organisations communautaires de l\u2019avenir\u00bb, explique Johanne Saltarelli, directrice g\u00e9n\u00e9rale de Jeunesse au Soleil<\/p>\n<p>L\u2019organisme a annonc\u00e9 aujourd\u2019hui avoir d\u00e9j\u00e0 amass\u00e9 9,8 millions $, soit 70% de son objectif.<\/p><p><br><\/p>\n<p><strong>Un appel \u00e0 la g\u00e9n\u00e9rosit\u00e9 de la communaut\u00e9<\/strong><\/p>\n<p>Jeunesse au soleil lance un appel \u00e0 la g\u00e9n\u00e9rosit\u00e9 du public et de la communaut\u00e9 d\u2019affaires afin de r\u00e9unir les 4.2 millions $ manquants. Le centre communautaire polyvalent est destin\u00e9 \u00e0 offrir des services bas\u00e9s sur les besoins des usagers, notamment l\u2019aide alimentaire, l\u2019aide aux enfants et aux \u00e9tudiants, l\u2019aide aux sinistr\u00e9s et aux victimes de crimes, l\u2019aide mat\u00e9rielle et financi\u00e8re, les programmations sportives, \u00e9ducatives et ax\u00e9es sur les loisirs.&nbsp;<\/p>\n<p>Ce projet jouera aussi un r\u00f4le important dans la r\u00e9duction de l\u2019empreinte environnementale de l\u2019organisme et s\u2019aligne avec les objectifs du Plan Climat 2020-2030 de la Ville de Montr\u00e9al. Il agira \u00e0 titre de mod\u00e8le social, communautaire et environnemental en proposant un mod\u00e8le qui vise \u00e0 promouvoir des valeurs d\u2019entraide, de collaboration et de saines habitudes de vie en communaut\u00e9, notamment en partageant ses locaux \u00e0 d\u2019autres organismes du quartier. De plus, l\u2019\u00e9difice m\u00eame deviendra un outil d\u2019enseignement et d\u2019apprentissage. Les jeunes et moins jeunes pourront y apprendre le fonctionnement des concepts innovants tels les panneaux solaires, la g\u00e9othermie et le verdissement des structures.&nbsp;&nbsp;<\/p>\n<p style=\"box-sizing: border-box; margin-top: 0px; margin-bottom: 0.9rem; color: #000000; font-family: Roboto, sans-serif; font-size: 16px; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-thickness: initial; text-decoration-style: initial; text-decoration-color: initial;\"><br><\/p>\n<p><strong style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: 1rem;\">Des porte-parole engag\u00e9s<\/strong><\/p>\n<p>L\u2019\u00e9quipe de Jeunesse au soleil est heureuse de compter sur des porte-parole engag\u00e9s, touch\u00e9s par la mission de l\u2019organisme et soucieux de s\u2019impliquer dans la vie des Montr\u00e9alais. Anthony Calvillo, Terry DiMonte, Meeker Guerrier, Tania Kontoyanni et Kim Richardson ont accept\u00e9 avec beaucoup de g\u00e9n\u00e9rosit\u00e9 de pr\u00eater leur nom et leur voix \u00e0 ce magnifique projet porteur pour la communaut\u00e9.<\/p>\n<p><strong><br><\/strong><\/p><p><strong>Comment donner ?<\/strong><\/p>\n<p>Les personnes qui souhaitent contribuer peuvent le faire sur la page batirjeunesseausoleil.org ou en contactant linda.bell@jas-sy.org.<\/p>\n<p>Tous les dons sont importants !<\/p>\n<p><strong><br><\/strong><\/p><p><strong>Le projet en quelques lignes :&nbsp;<\/strong><\/p>\n<p>Principales caract\u00e9ristiques du b\u00e2timent sur une surface de plus de 38 000 pieds carr\u00e9s :&nbsp;<\/p>\n<ul>\n<li style=\"list-style-type: none;\">&nbsp;<\/li>\n<li>Projet carboneutre<\/li>\n<li>Structure en bois<\/li>\n<li>Vingt-cinq puits de g\u00e9othermie&nbsp;<\/li>\n<li>Panneaux solaires<\/li>\n<li>Jardin sur le toit<\/li>\n<li>Gymnase et vestiaires<\/li>\n<li>Salles multifonctionnelles<\/li>\n<li>Une lumineuse banque alimentaire de style \u00e9picerie<\/li>\n<li>Des espaces pour la communaut\u00e9<\/li>\n<\/ul>\n<p><strong><br><\/strong><\/p><p><strong>Services offerts:<\/strong><\/p>\n<ul>\n<li style=\"list-style-type: none;\">&nbsp;<\/li>\n<li>D\u00e9pannage alimentaire<\/li>\n<li>Cuisine collective<\/li>\n<li>Agriculture urbaine<\/li>\n<li>Sports et Loisirs<\/li>\n<li>Tutorat, salle d\u2019\u00e9tudes<\/li>\n<li>Distribution de fournitures scolaires&nbsp;<\/li>\n<li>Aide aux sinistr\u00e9s<\/li>\n<li>Aide aux victimes de crime<\/li>\n<li>Programme-m\u00e9dicaments<\/li>\n<li>Aide vestimentaire<\/li>\n<\/ul>\n<figure><\/figure>\n<p><strong><br><\/strong><\/p><p><strong>\u00c9ch\u00e9ancier :<\/strong><\/p>\n<ul>\n<li style=\"list-style-type: none;\">&nbsp;<\/li>\n<li>D\u00e9but de la mise en chantier : hiver 2023-2024<\/li>\n<li>Ouverture pr\u00e9vue : printemps 2025<\/li>\n<li>Co\u00fbt total du projet $ : 31,5 M$<\/li>\n<li style=\"list-style-type: none;\">&nbsp;<\/li>\n<\/ul>\n<p>Tous les d\u00e9tails sont disponibles \u00e0&nbsp; : <strong>batirjeunesseausoleil.org<\/strong><\/p>\n<p><strong>\u00c0 propos de Jeunesse au soleil (Sun Youth)<\/strong><\/p>\n<p>Depuis 1954, nous prenons soin des Montr\u00e9alais en intervenant aupr\u00e8s des personnes et des familles d\u00e9munies. Nous fournissons une gamme de services d\u2019urgence visant \u00e0 assurer leurs besoins de base et \u00e0 maintenir leur int\u00e9grit\u00e9. Nous contribuons activement \u00e0 la pr\u00e9vention du crime et favorisons le d\u00e9veloppement physique et intellectuel des jeunes par l\u2019\u00e9ducation, le sport et les loisirs. Notre objectif fondamental est de soulager la pauvret\u00e9 et de pr\u00e9venir l\u2019exclusion. Nous sommes pr\u00e9sentement en campagne majeure de financement pour la construction d\u2019un nouvel \u00e9difice carboneutre \u00e0 partir d\u2019o\u00f9 tous les services seront offerts.&nbsp;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc8276b gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"cc8276b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t\n<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"cc8276b\" data-elementor-lightbox-title=\"6U4A2081\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTUzOCwidXJsIjoiaHR0cHM6XC9cL2JhdGlyamV1bmVzc2VhdXNvbGVpbC5vcmdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzAzXC82VTRBMjA4MS1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiY2M4Mjc2YiJ9\" href='https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2081-scaled.jpg'><img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2081-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2081-1024x683.jpg 1024w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2081-300x200.jpg 300w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2081-768x512.jpg 768w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2081-1536x1024.jpg 1536w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2081-2048x1365.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"cc8276b\" data-elementor-lightbox-title=\"6U4A2101\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0MCwidXJsIjoiaHR0cHM6XC9cL2JhdGlyamV1bmVzc2VhdXNvbGVpbC5vcmdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzAzXC82VTRBMjEwMS1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiY2M4Mjc2YiJ9\" href='https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2101-scaled.jpg'><img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2101-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2101-1024x683.jpg 1024w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2101-300x200.jpg 300w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2101-768x512.jpg 768w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2101-1536x1024.jpg 1536w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2101-2048x1365.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"cc8276b\" data-elementor-lightbox-title=\"6U4A2170\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0MiwidXJsIjoiaHR0cHM6XC9cL2JhdGlyamV1bmVzc2VhdXNvbGVpbC5vcmdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzAzXC82VTRBMjE3MC1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiY2M4Mjc2YiJ9\" href='https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2170-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2170-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2170-1024x683.jpg 1024w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2170-300x200.jpg 300w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2170-768x512.jpg 768w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2170-1536x1024.jpg 1536w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2170-2048x1365.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"cc8276b\" data-elementor-lightbox-title=\"6U4A2285\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0NiwidXJsIjoiaHR0cHM6XC9cL2JhdGlyamV1bmVzc2VhdXNvbGVpbC5vcmdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzAzXC82VTRBMjI4NS1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiY2M4Mjc2YiJ9\" href='https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2285-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2285-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2285-1024x683.jpg 1024w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2285-300x200.jpg 300w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2285-768x512.jpg 768w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2285-1536x1024.jpg 1536w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2285-2048x1365.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"cc8276b\" data-elementor-lightbox-title=\"6U4A2294\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0OCwidXJsIjoiaHR0cHM6XC9cL2JhdGlyamV1bmVzc2VhdXNvbGVpbC5vcmdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzAzXC82VTRBMjI5NC1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiY2M4Mjc2YiJ9\" href='https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2294-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2294-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2294-1024x683.jpg 1024w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2294-300x200.jpg 300w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2294-768x512.jpg 768w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2294-1536x1024.jpg 1536w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/6U4A2294-2048x1365.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"cc8276b\" data-elementor-lightbox-title=\"7U0A1335\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU1MCwidXJsIjoiaHR0cHM6XC9cL2JhdGlyamV1bmVzc2VhdXNvbGVpbC5vcmdcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzAzXC83VTBBMTMzNS1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiY2M4Mjc2YiJ9\" href='https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/7U0A1335-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/7U0A1335-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/7U0A1335-1024x683.jpg 1024w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/7U0A1335-300x200.jpg 300w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/7U0A1335-768x512.jpg 768w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/7U0A1335-1536x1024.jpg 1536w, https:\/\/batirjeunesseausoleil.org\/wp-content\/uploads\/2023\/03\/7U0A1335-2048x1365.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>C\u2019est sous le th\u00e8me \u00ab B\u00e2tir un avenir meilleur \u00bb que Jeunesse au soleil lance aujourd\u2019hui la premi\u00e8re campagne majeure de financement de son histoire pour la construction d\u2019un nouveau centre communautaire, compl\u00e8tement carboneutre, qui r\u00e9unira tous les services de l\u2019organisme sous un m\u00eame toit. La nouvelle maison de Jeunesse au soleil, dont l\u2019ouverture est [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1277,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-298","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/batirjeunesseausoleil.org\/fr\/wp-json\/wp\/v2\/posts\/298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/batirjeunesseausoleil.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/batirjeunesseausoleil.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/batirjeunesseausoleil.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/batirjeunesseausoleil.org\/fr\/wp-json\/wp\/v2\/comments?post=298"}],"version-history":[{"count":63,"href":"https:\/\/batirjeunesseausoleil.org\/fr\/wp-json\/wp\/v2\/posts\/298\/revisions"}],"predecessor-version":[{"id":2960,"href":"https:\/\/batirjeunesseausoleil.org\/fr\/wp-json\/wp\/v2\/posts\/298\/revisions\/2960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/batirjeunesseausoleil.org\/fr\/wp-json\/wp\/v2\/media\/1277"}],"wp:attachment":[{"href":"https:\/\/batirjeunesseausoleil.org\/fr\/wp-json\/wp\/v2\/media?parent=298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/batirjeunesseausoleil.org\/fr\/wp-json\/wp\/v2\/categories?post=298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/batirjeunesseausoleil.org\/fr\/wp-json\/wp\/v2\/tags?post=298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}